{"id":10111,"date":"2021-08-05T09:48:48","date_gmt":"2021-08-05T13:48:48","guid":{"rendered":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/?p=10111"},"modified":"2024-03-07T11:08:36","modified_gmt":"2024-03-07T16:08:36","slug":"nappe-phreatique-le-defi-qui-nous-attends","status":"publish","type":"post","link":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/nappe-phreatique-le-defi-qui-nous-attends\/","title":{"rendered":"Nappe Phr\u00e9atique | Le d\u00e9fi qui nous attends"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10111\" class=\"elementor elementor-10111\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a6392a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a6392a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec27bfe\" data-id=\"ec27bfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a1acdc elementor-widget elementor-widget-heading\" data-id=\"2a1acdc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nappe Phr\u00e9atique | Le d\u00e9fi qui nous attends<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2054d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2054d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa9474\" data-id=\"1aa9474\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f576b3c elementor-widget elementor-widget-text-editor\" data-id=\"f576b3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;type&quot;:&quot;text&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\" data-doc-id=\"1933082000001170002\" data-doc-type=\"writer\">Au cours des derni\u00e8res ann\u00e9es, plusieurs \u00e9tudes se sont pench\u00e9es sur l\u2019\u00e9tat des nappes phr\u00e9atiques. Ces r\u00e9servoirs naturels souterrains, qui se remplissent tr\u00e8s lentement gr\u00e2ce \u00e0 l\u2019eau de pluie et aux ruissellements, alimentent les puits et les sources en eau potable.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">M\u00eame si on ne peut d\u00e9terminer avec certitude quelle quantit\u00e9 d&rsquo;eau est disponible sur la plan\u00e8te, les scientifiques s&rsquo;entendent sur un point : Un nombre important de ces r\u00e9servoirs naturels sont surexploit\u00e9s.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">L&rsquo;augmentation de la population mondiale est l&rsquo;une des causes principales de cette p\u00e9nurie annonc\u00e9e. Depuis 1900, la population mondiale a tripl\u00e9, mais la consommation d&rsquo;eau, elle, a \u00e9t\u00e9 multipli\u00e9e par six. On pr\u00e9voit qu&rsquo;en 2050 il devrait y avoir 9,8 milliards d&rsquo;individus sur terre. Ce qui est 2,3 milliards de plus qu&rsquo;actuellement.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Plus de gens, donc plus de bouches \u00e0 nourrir, donc plus d&rsquo;agriculture. Et l&rsquo;agriculture est responsable de 70% des pr\u00e9l\u00e8vements d&rsquo;eau dans le monde.<span class=\"EOP\">\u00a0<\/span><\/p><p>De plus, des endroits d\u00e9sertiques sont devenus fertiles gr\u00e2ce au pompage des nappes phr\u00e9atiques ccomme l&rsquo;Arabie saoudite et, plus pr\u00e8s de nous, la r\u00e9gion de Las Vegas. Si vous \u00eates d\u00e9j\u00e0 all\u00e9 \u00e0 Las Vegas, vous avez vu les d\u00e9g\u00e2ts caus\u00e9s \u00e0 la Rivi\u00e8re Colorado ( \u00e0 lire: <span style=\"color: #000080;\"><a style=\"color: #000080;\" href=\"https:\/\/www.lemonde.fr\/m-le-mag\/article\/2019\/05\/27\/le-colorado-un-fleuve-en-peril_5467727_4500055.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lemonde.fr\/m-le-mag\/article\/2019\/05\/27\/le-colorado-un-fleuve-en-peril_5467727_4500055.html<\/a><\/span> )<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4126ece elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4126ece\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c22858\" data-id=\"4c22858\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73bb0d7 elementor-widget elementor-widget-text-editor\" data-id=\"73bb0d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Une image vaut mille mots<\/strong><\/p><p><span data-doc-id=\"1933082000001170002\" data-doc-type=\"writer\">Voici une photo du Lac Mead, qui est un r\u00e9servoir artificiel et <\/span>qui sert \u00e0 alimenter en eau les \u00c9tats de l&rsquo;Arizona, du Nevada et de la Californie, fournissant pr\u00e8s de 20 millions de personnes et de grandes surfaces agricoles. Le lac n&rsquo;a pas atteint sa pleine capacit\u00e9 depuis 1983 en raison d&rsquo;une combinaison de s\u00e9cheresse et d\u2019augmentation de la demande en eau. Et la d\u00e9marcation est tr\u00e8s nette!\u00a0\u00a0<\/p><p>Pendant ce temps, \u00e0 Vegas,\u00a0\u00a0qui est tout pr\u00e8s, tout roule comme si de rien n&rsquo;\u00e9tait&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66bd74a\" data-id=\"66bd74a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8f0bad elementor-widget elementor-widget-image\" data-id=\"d8f0bad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-1024x768.jpg\" class=\"attachment-large size-large wp-image-10112\" alt=\"\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-1024x768.jpg 1024w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-400x300.jpg 400w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-768x576.jpg 768w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-1536x1152.jpg 1536w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-2048x1536.jpg 2048w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/08\/ricardo-frantz-OfJVtZphM7c-unsplash-600x450.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eac73ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac73ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc6f4b4\" data-id=\"fc6f4b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bcee2c elementor-widget elementor-widget-text-editor\" data-id=\"3bcee2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;TeX Gyre Heros&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\" data-doc-id=\"1933082000001170002\" data-doc-type=\"writer\"><strong>Des solutions?<\/strong><\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;TeX Gyre Heros&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Les solutions existent&#8230;. mais il faudra changer nos m\u00e9thodes d&rsquo;agriculture.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;TeX Gyre Heros&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">L\u2019agriculture intensive et l\u2019utilisation accrue de l\u2019eau de pluie, ou m\u00eame des eaux us\u00e9es que l&rsquo;on utilise actuellement, devra faire place \u00e0 l&rsquo;agriculture de conservation.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;TeX Gyre Heros&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\"><strong>De quoi cela s&rsquo;agit-il?<\/strong><\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;TeX Gyre Heros&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(34, 34, 34)&quot;,&quot;size&quot;:&quot;12.75&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">L&rsquo;agriculture de conservation pr\u00e9voit le maintien d\u2019une couverture permanente du sol, un travail du sol minimal et la diversification des esp\u00e8ces v\u00e9g\u00e9tales. Elle permet d\u2019accro\u00eetre la biodiversit\u00e9 et stimule les processus biologiques naturels qui ont lieu au-dessus et en dessous de la surface du sol, ce qui contribue \u00e0 une utilisation plus efficace de l\u2019eau et des nutriments et permet d\u2019am\u00e9liorer durablement la production v\u00e9g\u00e9tale.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(0, 59, 67)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Plus de d\u00e9tails ici: <span style=\"color: #333399;\"><a style=\"color: #333399;\" href=\"http:\/\/www.fao.org\/conservation-agriculture\/overview\/what-is-conservation-agriculture\/fr\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.fao.org\/conservation-agriculture\/overview\/what-is-conservation-agriculture\/fr\/<\/a><\/span><\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(0, 59, 67)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\"><span class=\"EOP\">\u00a0<\/span>Nous le disons souvent, et les changements climatiques le prouvent : Souvenez-vous il y a 50 ans (pour les plus vieux), nous pouvions jouer dehors toute la journ\u00e9e sans probl\u00e8me, et certaines personnes se mettaient m\u00eame de l&rsquo;huile \u00e0 bronzer sur le corps. \u00c7a, c&rsquo;\u00e9tait il y a 40-50 ans! Imaginez maintenant l&rsquo;avenir dans 50 ans.<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Roboto&quot;,&quot;td&quot;:&quot;none&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(0, 59, 67)&quot;,&quot;size&quot;:&quot;12&quot;,&quot;fw_i&quot;:400,&quot;va&quot;:&quot;baseline&quot;,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Nous devons changer nos m\u00e9thodes, notre fa\u00e7on de consommer!<\/p><p>C&rsquo;est aussi le d\u00e9fi qui nous attend!\u00a0\u00a0Nos enfants et les enfants de nos enfants risquent fort de faire les frais de notre inaction d&rsquo;aujourd&rsquo;hui.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nappe Phr\u00e9atique | Le d\u00e9fi qui nous attends Au cours des derni\u00e8res ann\u00e9es, plusieurs \u00e9tudes se sont pench\u00e9es sur l\u2019\u00e9tat des nappes phr\u00e9atiques. Ces r\u00e9servoirs naturels souterrains, qui se remplissent tr\u00e8s lentement gr\u00e2ce \u00e0 l\u2019eau de pluie et aux ruissellements, alimentent les puits et les sources en eau potable. M\u00eame si on ne peut d\u00e9terminer [&hellip;]<\/p>","protected":false},"author":7,"featured_media":10112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10111"}],"collection":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/comments?post=10111"}],"version-history":[{"count":14,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10111\/revisions"}],"predecessor-version":[{"id":18547,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10111\/revisions\/18547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media\/10112"}],"wp:attachment":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media?parent=10111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/categories?post=10111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/tags?post=10111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}