{"id":10685,"date":"2022-01-21T09:26:19","date_gmt":"2022-01-21T14:26:19","guid":{"rendered":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/?p=10685"},"modified":"2024-03-08T15:03:52","modified_gmt":"2024-03-08T20:03:52","slug":"limportance-de-la-filtration-de-leau","status":"publish","type":"post","link":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/limportance-de-la-filtration-de-leau\/","title":{"rendered":"L&rsquo;importance de la filtration de l&rsquo;eau"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10685\" class=\"elementor elementor-10685\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-403144c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"403144c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9300105\" data-id=\"9300105\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23a7a73 elementor-widget elementor-widget-heading\" data-id=\"23a7a73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'importance de la filtration de l'eau<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6a378d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6a378d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-347581a\" data-id=\"347581a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7402be2 elementor-widget elementor-widget-text-editor\" data-id=\"7402be2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-doc-id=\"1933082000001909001\" data-doc-type=\"writer\">Par d\u00e9finition, <\/span>l&rsquo;objectif de la filtration est de purifier votre eau. Elle permet d&rsquo;\u00e9liminer \u00e0 la fois les polluants chimiques (nitrates, pesticides, plombs et autre m\u00e9taux lourds) et \u00e9galement l&rsquo;odeur et le go\u00fbt chlor\u00e9, caract\u00e9ristiques de l&rsquo;eau du robinet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71d8e49 elementor-widget elementor-widget-image\" data-id=\"71d8e49\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/01\/filtration-eau.jpg\" class=\"attachment-large size-large wp-image-10690\" alt=\"\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/01\/filtration-eau.jpg 850w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/01\/filtration-eau-400x267.jpg 400w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/01\/filtration-eau-768x512.jpg 768w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/01\/filtration-eau-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b922519 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b922519\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff0fe95\" data-id=\"ff0fe95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9be2f8b elementor-widget elementor-widget-heading\" data-id=\"9be2f8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L' objectif \u200bSource Om\u00e9ga<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308ce43 elementor-widget elementor-widget-text-editor\" data-id=\"308ce43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-line-height=\"1.2\">Depuis ses d\u00e9buts, en 1990, notre entreprise a compris tr\u00e8s rapidement qu&rsquo;un syst\u00e8me d&rsquo;abreuvoir permettrait aux entreprises et aux municipalit\u00e9s d&rsquo;\u00e9liminer les r\u00e9servoirs munis de grosses bouteilles de 18 litres qui sont une source de pollution incroyable. Imaginez la quantit\u00e9 de plastique utilis\u00e9e, la pollution li\u00e9e au transport par camion, ainsi que les autres co\u00fbts connexes ( Bris des routes, pi\u00e8ces de camions etc )\u00a0\u00a0&#8211; D&rsquo;autant plus que ces camions roulaient \u00ab par-dessus \u00bb des syst\u00e8mes d&rsquo;aqueducs d\u00e9j\u00e0 en place et qui acheminent l&rsquo;eau de fa\u00e7on naturelle et beaucoup plus rapidement!<\/p><p class=\"zw-paragraph heading0\" data-header=\"0\" data-textformat=\"{\" data-margin-bottom=\"0pt\" data-hd-info=\"0\" data-line-height=\"1.2\">Bref, nous \u00e9tions bien loin d&rsquo;une \u00e9conomie circulaire.Et avouez que c&rsquo;est paradoxal, toute cette pollution caus\u00e9e par un produit aussi naturel que l&rsquo;eau.<\/p><p class=\"zw-paragraph\" data-textformat=\"{\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Avec nos abreuvoirs et nos refroidisseurs, nous avons donc couvert un besoin qui, en plus de produire une eau de tr\u00e8s grande qualit\u00e9, aide la plan\u00e8te en \u00e9liminant les transports, plastiques et perte de temps de l&rsquo;\u00e9quation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b5641b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b5641b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1adb954\" data-id=\"1adb954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d6e6d elementor-widget elementor-widget-heading\" data-id=\"26d6e6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le r\u00e9servoir et le go\u00fbt de l'eau<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-569f4f5 elementor-widget elementor-widget-text-editor\" data-id=\"569f4f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"zw-paragraph\" data-textformat=\"{\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\"><span class=\"EOP\">\u00a0<\/span>Notre expertise dans notre domaine nous a amen\u00e9 \u00e0 vous offrir des produits de qualit\u00e9 sup\u00e9rieure, en commen\u00e7ant par le r\u00e9servoir de nos appareils.<\/p><p class=\"zw-paragraph\" data-textformat=\"{\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Vous avez certainement d\u00e9j\u00e0 bu une eau avec un go\u00fbt infect provenant d&rsquo;un abreuvoir, n&rsquo;est-ce pas? Sachez que le r\u00e9servoir en est tr\u00e8s certainement la cause. En effet, un abreuvoir muni d&rsquo;un r\u00e9servoir en cuivre am\u00e8nera un go\u00fbt souvent m\u00e9tallique, ce qui vous occasionnera une belle grimace!<\/p><p>C&rsquo;est pourquoi les appareils de Source Om\u00e9ga sont livr\u00e9s avec des r\u00e9servoirs en acier inoxydable. Si vous vous entra\u00eenez et que vous avez fait l&rsquo;achat d&rsquo;une bouteille en acier inoxydable au lieu de la bouteille de plastique, vous comprenez tr\u00e8s bien que l&rsquo;inox va conserver intact le bon go\u00fbt de l&rsquo;eau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a8b55b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a8b55b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d35a933\" data-id=\"d35a933\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfb3468 elementor-widget elementor-widget-heading\" data-id=\"bfb3468\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre syst\u00e8me de filtration - Son importance capitale!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7ead75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7ead75\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0835e73\" data-id=\"0835e73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-add1e2a elementor-widget elementor-widget-image\" data-id=\"add1e2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"419\" height=\"410\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/01\/filtre-menu.png\" class=\"attachment-large size-large wp-image-8415\" alt=\"\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/01\/filtre-menu.png 419w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2021\/01\/filtre-menu-300x294.png 300w\" sizes=\"(max-width: 419px) 100vw, 419px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-daa651b\" data-id=\"daa651b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80bae2e elementor-widget elementor-widget-text-editor\" data-id=\"80bae2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Arimo&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(32, 33, 36)&quot;,&quot;size&quot;:&quot;12.00&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;fw_i&quot;:400,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\" data-doc-id=\"1933082000001909001\" data-doc-type=\"writer\">Pour monsieur et madame tout le monde \u00e0 la maison, vous connaissez \u00e9videmment les produits de type Brita, qui demeurent un moyen fiable d&rsquo;am\u00e9liorer le go\u00fbt et l&rsquo;odeur de l&rsquo;eau. \u00c0 condition de changer le filtre au charbon r\u00e9guli\u00e8rement!<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Arimo&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(32, 33, 36)&quot;,&quot;size&quot;:&quot;12.00&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;fw_i&quot;:400,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Ce qui nous am\u00e8ne \u00e0 un point essentiel: la filtration!<\/p><p class=\"zw-paragraph\" data-textformat=\"{&quot;ff&quot;:&quot;Arimo&quot;,&quot;fv&quot;:&quot;normal&quot;,&quot;td&quot;:&quot;none&quot;,&quot;cs&quot;:&quot;0pt&quot;,&quot;fw&quot;:&quot;none&quot;,&quot;fgc&quot;:&quot;rgb(32, 33, 36)&quot;,&quot;size&quot;:&quot;12.00&quot;,&quot;va&quot;:&quot;baseline&quot;,&quot;fw_i&quot;:400,&quot;type&quot;:&quot;text&quot;,&quot;fs&quot;:&quot;normal&quot;,&quot;bgc&quot;:&quot;rgb(255, 255, 255)&quot;}\" data-margin-bottom=\"0pt\" data-line-height=\"1.2\">Nous avons mis au point un syst\u00e8me de triple filtration qui vous offre une eau au go\u00fbt pur! Cette triple filtration ( filtre \u00e0 s\u00e9diment,\u00a0\u00a0filtre adoucisseur et filtre au charbon ) est un \u00e9l\u00e9ment essentiel de la qualit\u00e9 de l&rsquo;eau que vous boirez.<\/p><p>Et tout comme les filtres de type Brita pour la maison, il est absolument essentiel de changer ces filtres r\u00e9guli\u00e8rement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;importance de la filtration de l&rsquo;eau Par d\u00e9finition, l&rsquo;objectif de la filtration est de purifier votre eau. Elle permet d&rsquo;\u00e9liminer \u00e0 la fois les polluants chimiques (nitrates, pesticides, plombs et autre m\u00e9taux lourds) et \u00e9galement l&rsquo;odeur et le go\u00fbt chlor\u00e9, caract\u00e9ristiques de l&rsquo;eau du robinet. L&rsquo; objectif \u200bSource Om\u00e9ga Depuis ses d\u00e9buts, en 1990, notre [&hellip;]<\/p>","protected":false},"author":7,"featured_media":10690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10685"}],"collection":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/comments?post=10685"}],"version-history":[{"count":32,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10685\/revisions"}],"predecessor-version":[{"id":18594,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/10685\/revisions\/18594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media\/10690"}],"wp:attachment":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media?parent=10685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/categories?post=10685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/tags?post=10685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}