{"id":12129,"date":"2022-09-13T09:45:01","date_gmt":"2022-09-13T13:45:01","guid":{"rendered":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/?p=12129"},"modified":"2024-03-11T10:44:52","modified_gmt":"2024-03-11T14:44:52","slug":"le-choix-source-omega-une-question-de-securite","status":"publish","type":"post","link":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/le-choix-source-omega-une-question-de-securite\/","title":{"rendered":"Le choix Source Om\u00e9ga | Une question de s\u00e9curit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12129\" class=\"elementor elementor-12129\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a5f61f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a5f61f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-131718f\" data-id=\"131718f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b12e29 elementor-widget elementor-widget-heading\" data-id=\"8b12e29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le choix Source Om\u00e9ga | Une question de s\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-411b832 elementor-widget elementor-widget-text-editor\" data-id=\"411b832\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"\">Quand notre entreprise a vu le jour en 1990, nous nous sommes aper\u00e7us tr\u00e8s rapidement que la s\u00e9curit\u00e9 de nos clients devenait une de nos priorit\u00e9s.\u00a0Nous avons tous v\u00e9cu un d\u00e9g\u00e2t d\u2019eau au moins une fois dans notre vie. Et, loi de Murphy oblige, il est tr\u00e8s, tr\u00e8s rare que cela arrive quand nous sommes \u00e0 proximit\u00e9 de la catastrophe.\u00a0<br \/><br \/><\/div><div class=\"\">Comme les piles de nos avertisseurs de fum\u00e9e qui se font un malin plaisir de nous r\u00e9veiller la nuit, c\u2019est aussi la nuit ou durant le week-end, ou pire, pendant nos vacances, que les accidents se produisent avec la plomberie.\u00a0<\/div><p class=\"\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65a5f11 elementor-widget elementor-widget-heading\" data-id=\"65a5f11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 chacun son m\u00e9tier <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08c624f elementor-widget elementor-widget-text-editor\" data-id=\"08c624f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9videmment, notre secteur d\u2019activit\u00e9 c\u2019est l\u2019eau! Nous installons et entretenons des milliers d\u2019abreuvoirs ou refroidisseurs d\u2019eau partout au Qu\u00e9bec. On a vu des installations de \u00ab cabochons \u00bb qui par exemple faisaient passer la tuyauterie par le plafond avec des tuyaux de plastique, ce qui est ill\u00e9gal. ( Et inutile de vous dire l\u2019\u00e9tendue des d\u00e9g\u00e2ts possibles si un bris survenait! ).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97d96a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97d96a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9460f51\" data-id=\"9460f51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2398cc1 elementor-widget elementor-widget-text-editor\" data-id=\"2398cc1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b class=\"\">Abreuvoirs et filtrations<\/b><\/h2><div class=\"\"><p>Lors de l\u2019installation de l\u2019un de nos appareils, cela signifie l\u2019installation de raccords et de joints. Inutile de dire que les pr\u00e9cautions sont prises pour \u00e9viter des accidents. Mais des accidents \u00e7a arrive.<\/p><p>L\u2019id\u00e9e est donc de r\u00e9duire au minimum les cons\u00e9quences. C\u2019est pourquoi nous avons ajout\u00e9 \u00e0 chacune de nos installations un d\u00e9tecteur de fuites d\u2019eau, le SOV-25!\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45e2290\" data-id=\"45e2290\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53c4339 elementor-widget elementor-widget-image\" data-id=\"53c4339\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-1024x768.jpg\" class=\"attachment-large size-large wp-image-12132\" alt=\"\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-1024x768.jpg 1024w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-400x300.jpg 400w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-768x576.jpg 768w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-1536x1152.jpg 1536w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25-600x450.jpg 600w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/InstallationSOV25.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da8f8e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da8f8e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64f801d\" data-id=\"64f801d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4a89a elementor-widget elementor-widget-heading\" data-id=\"3b4a89a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour dormir sur vos 2 oreilles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652a8a9 elementor-widget elementor-widget-text-editor\" data-id=\"652a8a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"\"><p>Le SOV-25 est aliment\u00e9 par une pile 9V, donc ind\u00e9pendant du syst\u00e8me \u00e9lectrique. Lorsqu\u2019une fuite d\u2019eau survient, ce dispositif fermera automatiquement la valve raccord\u00e9e \u00e0 votre abreuvoir. Encore faut-il qu\u2019il soit bien install\u00e9!<\/p><\/div><div class=\"\">Lors de l\u2019installation de ce dispositif, il arrive que le plancher ne soit pas de niveau. Si le SOV-25 n\u2019est pas install\u00e9 l\u00e0 o\u00f9 l\u2019eau se formera, son utilit\u00e9 devient nulle! C\u2019est pourquoi nous avons ajout\u00e9 un tapis de caoutchouc qui servira de premi\u00e8re ligne de protection.\u00a0<\/div><div class=\"\"><img decoding=\"async\" class=\"alignright wp-image-12137\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-scaled.jpg\" alt=\"Tapis SOV25\" width=\"300\" height=\"225\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-scaled.jpg 2560w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-400x300.jpg 400w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-1024x768.jpg 1024w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-768x576.jpg 768w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-1536x1152.jpg 1536w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-2048x1536.jpg 2048w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2022\/09\/20220419_104133-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"\">Comme vous le voyez, le tapis est install\u00e9 sous l\u2019appareil et devient le senseur qui d\u00e9tectera l\u2019eau si elle coule. Gr\u00e2ce \u00e0 la profondeur du tapis, s\u2019il y a une l\u00e9g\u00e8re inclinaison du plancher, l\u2019eau sera quand m\u00eame retenue dans le tapis, le temps que le niveau de l\u2019eau se rende au senseur.\u00a0<\/div><div class=\"\">Un papier imbibant est \u00e9galement plac\u00e9 sous le tapis de caoutchouc.\u00a0<\/div><div class=\"\" style=\"text-align: left;\"><p>Nous prenons vraiment toutes les mesures pour que l\u2019accident ne soit finalement qu\u2019un incident! \u00c0 noter \u00e9galement que la valve du SOV-25 est retenue ouverte par la pile 9V. Si celle-ci devient faible, ou si les capteurs touchent \u00e0 l\u2019eau, la valve fermera l\u2019eau et vous entendrez une alarme sonore.\u00a0<\/p><p>Pour en savoir plus sur notre d\u00e9tecteur de fuites d\u2019eau, n\u2019h\u00e9sitez pas \u00e0 faire une demande de devis en cliquant ici: <a href=\"https:\/\/boutique-sourceomega.com\/produit\/detecteur-de-fuite-deau\/\" target=\"_blank\" rel=\"noopener\">d\u00e9tecteur de fuites d&rsquo;eau<\/a><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le choix Source Om\u00e9ga | Une question de s\u00e9curit\u00e9 Quand notre entreprise a vu le jour en 1990, nous nous sommes aper\u00e7us tr\u00e8s rapidement que la s\u00e9curit\u00e9 de nos clients devenait une de nos priorit\u00e9s.\u00a0Nous avons tous v\u00e9cu un d\u00e9g\u00e2t d\u2019eau au moins une fois dans notre vie. Et, loi de Murphy oblige, il est [&hellip;]<\/p>","protected":false},"author":7,"featured_media":9132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/12129"}],"collection":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/comments?post=12129"}],"version-history":[{"count":23,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/12129\/revisions"}],"predecessor-version":[{"id":18598,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/12129\/revisions\/18598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media\/9132"}],"wp:attachment":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media?parent=12129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/categories?post=12129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/tags?post=12129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}