{"id":6201,"date":"2019-11-26T11:07:33","date_gmt":"2019-11-26T16:07:33","guid":{"rendered":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/?p=6201"},"modified":"2024-04-04T08:04:47","modified_gmt":"2024-04-04T12:04:47","slug":"suivez-nous-dans-lelimination-du-plastique-a-usage-unique","status":"publish","type":"post","link":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/suivez-nous-dans-lelimination-du-plastique-a-usage-unique\/","title":{"rendered":"Suivez-nous dans l\u2019\u00e9limination du plastique \u00e0 usage unique!"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6201\" class=\"elementor elementor-6201\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7858048 e-flex e-con-boxed e-con e-parent\" data-id=\"7858048\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-881f86a elementor-widget elementor-widget-heading\" data-id=\"881f86a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suivez-nous dans l\u2019\u00e9limination du plastique \u00e0 usage unique!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62eb2c78 e-flex e-con-boxed e-con e-parent\" data-id=\"62eb2c78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7323318c elementor-widget elementor-widget-text-editor\" data-id=\"7323318c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>De nos jours, l\u2019environnement est de plus en plus au c\u0153ur de nombreux d\u00e9bats. La g\u00e9n\u00e9ration actuelle cherche par plusieurs moyens d\u2019aider notre belle plan\u00e8te Terre. Que ce soit par la pr\u00e9sence croissante sur nos routes de v\u00e9hicules \u00e9lectriques ou l\u2019intention d&rsquo;\u00e9liminer les plastiques \u00e0 usage unique d&rsquo;ici 2021, nous essayons tous, individuellement et collectivement, de faire notre bout de chemin. Le plastique prend plusieurs centaines d\u2019ann\u00e9es, voir un mill\u00e9naire, avant de se d\u00e9composer et, durant ce temps, les ravages qu\u2019il fait sont plus que consid\u00e9rables.<\/p>\n<hr class=\"wp-block-separator is-style-wide\" \/>\n<h2 class=\"wp-block-heading\"><strong>Soyons \u00e9co-responsable<\/strong>s<\/h2>\n\n<p>Source Om\u00e9ga se d\u00e9finit comme une entreprise avant-gardiste qui contribue depuis pr\u00e8s de 30 ans aux mouvements \u00e9cologiques. Nous offrons des solutions aux entreprises afin d\u2019\u00e9liminer la consommation de bouteilles d\u2019eau jetables tout en gardant le go\u00fbt de l\u2019eau agr\u00e9able en bouche. Nous sommes l\u00e0 pour vous aider \u00e0 aller de l\u2019avant vers la r\u00e9alit\u00e9 du z\u00e9ro d\u00e9chet.<\/p>\n<p>Nous avons pour vous plusieurs solutions simples et concr\u00e8tes afin de contribuer \u00e0 r\u00e9duire la quantit\u00e9 de bouteilles d\u2019eau dans votre entreprise, tout en gardant \u00e0 c\u0153ur la qualit\u00e9 d\u2019eau offerte \u00e0 vos employ\u00e9s et vos clients.<\/p>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/product\/so-2035\/\"><img decoding=\"async\" class=\"wp-image-989\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2018\/02\/SO-2035.png\" alt=\"\" width=\"106\" height=\"292\" \/><\/a><\/figure>\n<\/div>\n\n<p>Ce refroidisseur debout s\u2019harmonisera parfaitement \u00e0 votre d\u00e9cor gr\u00e2ce \u00e0 sa couleur neutre. Il sera parfait afin d\u2019ajouter une touche d\u2019\u00e9l\u00e9gance dans votre salle d\u2019attente et dans votre salle de conf\u00e9rence. Le <a href=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/refroidisseur\/so-2035\/\">SO-2035<\/a> offre de l\u2019eau froide, chaude et temp\u00e9r\u00e9e. Cet appareil est donc id\u00e9al pour les breuvages frais durant les canicules d\u2019\u00e9t\u00e9 et les breuvages chauds durant le temps rude d\u2019hiver. Il vient avec la triple filtration, le d\u00e9tecteur de fuite d\u2019eau et une garantie conditionnelle de 7 ans.<\/p>\n<p>Si vous manquez de place au sol afin d\u2019ajouter le SO-2035 \u00e0 votre espace, sachez que nous offrons un mod\u00e8le comparable qui se d\u00e9pose sur le comptoir, soit le SO-519.<\/p>\n<p>\u00a0<\/p>\n\n<div class=\"wp-block-button\">Demandez une soumission pour ce refroidisseur debout<\/div>\n<hr class=\"wp-block-separator is-style-wide\" \/>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/product\/so-311\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-383\" src=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2017\/10\/Refroidisseur-sous-\u00e9vier-so-140-1.png\" alt=\"\" width=\"387\" height=\"281\" srcset=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2017\/10\/Refroidisseur-sous-\u00e9vier-so-140-1.png 550w, https:\/\/backup.sourceomega-13730204208.futehost.ca\/wp-content\/uploads\/2017\/10\/Refroidisseur-sous-\u00e9vier-so-140-1-300x218.png 300w\" sizes=\"(max-width: 387px) 100vw, 387px\" \/><\/a><\/figure>\n<\/div>\n\n<p>Cet appareil se place discr\u00e8tement sous l\u2019\u00e9vier, donc il est id\u00e9al pour les espaces aux comptoirs restreints. \u00c9galement \u00e9quip\u00e9 de la triple filtration, du d\u00e9tecteur de fuite et de la garantie conditionnelle de 7 ans, le <a href=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/refroidisseur\/so-140\/\">SO-140<\/a> est id\u00e9al pour la cuisinette de vos employ\u00e9s.<\/p>\n<p>Il peut facilement s\u2019installer en duo avec le <a href=\"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/abreuvoir\/so-3004\/\">SO-3004<\/a> qui offre de l\u2019eau chaude, temp\u00e9rature parfaite pour vous faire du th\u00e9 en tout temps.<\/p>\n<p>\u00a0<\/p>\n\n<div class=\"wp-block-button\">Demandez une soumission pour ce refroidisseur sous-\u00e9vier<\/div>\n<hr class=\"wp-block-separator is-style-wide\" \/>\n<h2><strong>\u00c9liminons le plastique \u00e0 usage unique!<\/strong><\/h2>\n<p><b>Faisons tous notre part!<\/b><\/p>\n<p>La majorit\u00e9 des produits de Source Om\u00e9ga est munie d\u2019une triple filtration et d\u2019un d\u00e9tecteur de fuite d\u2019eau. En tant que d\u00e9cideur, vous pourrez offrir une eau aussi bonne que celle embouteill\u00e9e \u00e0 tous ceux qui vous visiteront. Nous incluons aussi un d\u00e9tecteur de fuite d\u2019eau avec nos appareils afin de contribuer \u00e0 votre tranquillit\u00e9 d\u2019esprit.<\/p>\n<p>Afin de faire notre part dans cette collectivit\u00e9, Source Om\u00e9ga a r\u00e9cemment commenc\u00e9 le renouvellement de sa flotte automobile. \u00c0 chaque fois que nous devons faire le remplacement d\u2019un v\u00e9hicule, nous choisissons des v\u00e9hicules hybrides, hybrides branchables ou \u00e9lectriques.<\/p>\n<p>Contactez-nous afin qu\u2019un de nos repr\u00e9sentants puisse trouver avec vous le mod\u00e8le qui remplira parfaitement vos besoins.<\/p>\n<p>Embarquer avec nous dans la vague de changements \u00e9cologiques!<\/p>\n<p>\u00a0<\/p>\n\n<p><em>Sources\u00a0:\u00a0 <\/em><br \/><a href=\"https:\/\/www.canalvie.com\/maison\/organisation\/comment-reduire-consommation-plastique-1.3752400\" target=\"_blank\" rel=\"noopener\">https:\/\/www.canalvie.com\/maison\/organisation\/comment-reduire-consommation-plastique-1.3752400<\/a><\/p>\n\n<p><a href=\"https:\/\/www.lapresse.ca\/actualites\/environnement\/201906\/10\/01-5229513-les-plastiques-a-usage-unique-interdits-des-2021.php\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lapresse.ca\/actualites\/environnement\/201906\/10\/01-5229513-les-plastiques-a-usage-unique-interdits-des-2021.php<\/a><\/p>\n\n<p>\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Suivez-nous dans l\u2019\u00e9limination du plastique \u00e0 usage unique! Soyons \u00e9co-responsables Sources\u00a0:\u00a0 https:\/\/www.canalvie.com\/maison\/organisation\/comment-reduire-consommation-plastique-1.3752400 https:\/\/www.lapresse.ca\/actualites\/environnement\/201906\/10\/01-5229513-les-plastiques-a-usage-unique-interdits-des-2021.php \u00a0<\/p>","protected":false},"author":7,"featured_media":6212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/6201"}],"collection":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/comments?post=6201"}],"version-history":[{"count":41,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/6201\/revisions"}],"predecessor-version":[{"id":19323,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/posts\/6201\/revisions\/19323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media\/6212"}],"wp:attachment":[{"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/media?parent=6201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/categories?post=6201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/backup.sourceomega-13730204208.futehost.ca\/en\/wp-json\/wp\/v2\/tags?post=6201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}